{"id":10002197,"date":"2023-02-27T17:44:55","date_gmt":"2023-02-27T22:44:55","guid":{"rendered":"https:\/\/www.arc-hss.ca\/event\/twisted-stitchers-candiac-5\/"},"modified":"2023-02-27T17:46:00","modified_gmt":"2023-02-27T22:46:00","slug":"twisted-stitchers-candiac-5","status":"publish","type":"tribe_events","link":"https:\/\/arc-hss.ca\/fr\/event\/twisted-stitchers-candiac-5\/2023-03-14\/","title":{"rendered":"Twisted Stitchers @Candiac"},"content":{"rendered":"<p>Twisted Stitchers<\/p>\n<p>Beautiful things come together one stitch at a time with this weekly activity at the Candiac office.<\/p>\n<p>To register, email <a href=\"mailto:candiac@arc-hss.ca\">candiac@arc-hss.ca<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Twisted Stitchers Beautiful things come together one stitch at a <\/p>\n","protected":false},"author":1,"featured_media":14006,"template":"","meta":{"_acf_changed":false,"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[],"tribe_events_cat":[],"class_list":["post-10002197","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe-recurring-event","tribe-recurring-event-parent"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Twisted Stitchers @Candiac - ARC<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/arc-hss.ca\/fr\/event\/twisted-stitchers-candiac-5\/2023-03-14\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Twisted Stitchers @Candiac - ARC\" \/>\n<meta property=\"og:description\" content=\"Twisted Stitchers Beautiful things come together one stitch at a\" \/>\n<meta property=\"og:url\" content=\"https:\/\/arc-hss.ca\/fr\/event\/twisted-stitchers-candiac-5\/2023-03-14\/\" \/>\n<meta property=\"og:site_name\" content=\"ARC\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-27T22:46:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/arc-hss.ca\/wp-content\/uploads\/2023\/01\/twisted-stitchers.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"940\" \/>\n\t<meta property=\"og:image:height\" content=\"788\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/arc-hss.ca\\\/fr\\\/event\\\/twisted-stitchers-candiac-5\\\/2023-03-14\\\/\",\"url\":\"https:\\\/\\\/arc-hss.ca\\\/fr\\\/event\\\/twisted-stitchers-candiac-5\\\/2023-03-14\\\/\",\"name\":\"Twisted Stitchers @Candiac - ARC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/arc-hss.ca\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/arc-hss.ca\\\/fr\\\/event\\\/twisted-stitchers-candiac-5\\\/2023-03-14\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/arc-hss.ca\\\/fr\\\/event\\\/twisted-stitchers-candiac-5\\\/2023-03-14\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/arc-hss.ca\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/twisted-stitchers.jpg\",\"datePublished\":\"2023-02-27T22:44:55+00:00\",\"dateModified\":\"2023-02-27T22:46:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/arc-hss.ca\\\/fr\\\/event\\\/twisted-stitchers-candiac-5\\\/2023-03-14\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/arc-hss.ca\\\/fr\\\/event\\\/twisted-stitchers-candiac-5\\\/2023-03-14\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/arc-hss.ca\\\/fr\\\/event\\\/twisted-stitchers-candiac-5\\\/2023-03-14\\\/#primaryimage\",\"url\":\"https:\\\/\\\/arc-hss.ca\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/twisted-stitchers.jpg\",\"contentUrl\":\"https:\\\/\\\/arc-hss.ca\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/twisted-stitchers.jpg\",\"width\":940,\"height\":788},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/arc-hss.ca\\\/fr\\\/event\\\/twisted-stitchers-candiac-5\\\/2023-03-14\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/arc-hss.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c9v\u00e8nements\",\"item\":\"https:\\\/\\\/arc-hss.ca\\\/fr\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Twisted Stitchers @Candiac\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/arc-hss.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/arc-hss.ca\\\/fr\\\/\",\"name\":\"ARC\",\"description\":\"Assistance and Referral Centre\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/arc-hss.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Twisted Stitchers @Candiac - ARC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/arc-hss.ca\/fr\/event\/twisted-stitchers-candiac-5\/2023-03-14\/","og_locale":"fr_FR","og_type":"article","og_title":"Twisted Stitchers @Candiac - ARC","og_description":"Twisted Stitchers Beautiful things come together one stitch at a","og_url":"https:\/\/arc-hss.ca\/fr\/event\/twisted-stitchers-candiac-5\/2023-03-14\/","og_site_name":"ARC","article_modified_time":"2023-02-27T22:46:00+00:00","og_image":[{"width":940,"height":788,"url":"https:\/\/arc-hss.ca\/wp-content\/uploads\/2023\/01\/twisted-stitchers.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/arc-hss.ca\/fr\/event\/twisted-stitchers-candiac-5\/2023-03-14\/","url":"https:\/\/arc-hss.ca\/fr\/event\/twisted-stitchers-candiac-5\/2023-03-14\/","name":"Twisted Stitchers @Candiac - ARC","isPartOf":{"@id":"https:\/\/arc-hss.ca\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/arc-hss.ca\/fr\/event\/twisted-stitchers-candiac-5\/2023-03-14\/#primaryimage"},"image":{"@id":"https:\/\/arc-hss.ca\/fr\/event\/twisted-stitchers-candiac-5\/2023-03-14\/#primaryimage"},"thumbnailUrl":"https:\/\/arc-hss.ca\/wp-content\/uploads\/2023\/01\/twisted-stitchers.jpg","datePublished":"2023-02-27T22:44:55+00:00","dateModified":"2023-02-27T22:46:00+00:00","breadcrumb":{"@id":"https:\/\/arc-hss.ca\/fr\/event\/twisted-stitchers-candiac-5\/2023-03-14\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/arc-hss.ca\/fr\/event\/twisted-stitchers-candiac-5\/2023-03-14\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/arc-hss.ca\/fr\/event\/twisted-stitchers-candiac-5\/2023-03-14\/#primaryimage","url":"https:\/\/arc-hss.ca\/wp-content\/uploads\/2023\/01\/twisted-stitchers.jpg","contentUrl":"https:\/\/arc-hss.ca\/wp-content\/uploads\/2023\/01\/twisted-stitchers.jpg","width":940,"height":788},{"@type":"BreadcrumbList","@id":"https:\/\/arc-hss.ca\/fr\/event\/twisted-stitchers-candiac-5\/2023-03-14\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/arc-hss.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"\u00c9v\u00e8nements","item":"https:\/\/arc-hss.ca\/fr\/events\/"},{"@type":"ListItem","position":3,"name":"Twisted Stitchers @Candiac"}]},{"@type":"WebSite","@id":"https:\/\/arc-hss.ca\/fr\/#website","url":"https:\/\/arc-hss.ca\/fr\/","name":"ARC","description":"Assistance and Referral Centre","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/arc-hss.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/arc-hss.ca\/fr\/wp-json\/wp\/v2\/tribe_events\/10002197","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/arc-hss.ca\/fr\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/arc-hss.ca\/fr\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/arc-hss.ca\/fr\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/arc-hss.ca\/fr\/wp-json\/wp\/v2\/tribe_events\/10002197\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/arc-hss.ca\/fr\/wp-json\/wp\/v2\/media\/14006"}],"wp:attachment":[{"href":"https:\/\/arc-hss.ca\/fr\/wp-json\/wp\/v2\/media?parent=10002197"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/arc-hss.ca\/fr\/wp-json\/wp\/v2\/tags?post=10002197"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/arc-hss.ca\/fr\/wp-json\/wp\/v2\/tribe_events_cat?post=10002197"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}